{"id":278,"date":"2023-01-31T19:26:14","date_gmt":"2023-01-31T19:26:14","guid":{"rendered":"https:\/\/ingood.org\/?p=278"},"modified":"2023-10-27T09:50:08","modified_gmt":"2023-10-27T09:50:08","slug":"credito-di-imposta-formazione4-0","status":"publish","type":"post","link":"https:\/\/vca.partners\/en\/credito-di-imposta-formazione4-0\/","title":{"rendered":"Credito di&#8217;Imposta Formazione 4.0"},"content":{"rendered":"<p id=\"viewer-373ph\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Il <a class=\"_3Bkfb _1lsz7\" href=\"https:\/\/www.mise.gov.it\/index.php\/it\/incentivi\/impresa\/credito-d-imposta-formazione\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-hook=\"linkViewer\"><u class=\"_3zM-5\">credito d\u2019imposta Formazione 4.0<\/u><\/a> \u00e8 una misura agevolativa nazionale rivolta a tutte le imprese con lo scopo di stimolare e incentivare gli investimenti nella formazione del personale sulle materie inerenti alle tecnologie rilevanti, per favorire la trasformazione digitale.<\/span><\/p>\n<p id=\"viewer-119vq\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Il credito d\u2019imposta Formazione 4.0 \u00e8 utilizzabile in compensazione F24 a decorrere dal periodo di imposta successivo a quello di sostenimento delle spese ammissibili:<\/span><\/p>\n<ul class=\"public-DraftStyleDefault-ul\">\n<li id=\"viewer-e0od\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size public-DraftStyleDefault-reset _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">costo aziendale riferito alle ore o alle giornate di formazione;<\/p>\n<\/li>\n<li id=\"viewer-7ft8c\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">spese relative al personale dipendente impegnato nelle attivit\u00e0 di formazione ammissibili;<\/p>\n<\/li>\n<li id=\"viewer-bq021\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">spese relative al personale dipendente occupato in uno degli ambiti aziendali individuati nell\u2019allegato A della legge n. 205\/2017 e che partecipi in veste di docente o tutor alle attivit\u00e0 di formazione;<\/p>\n<\/li>\n<li id=\"viewer-701jb\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">attivit\u00e0 di formazione erogate da soggetti esterni all\u2019impresa, quali Istituti tecnici superiori, Universit\u00e0 pubbliche o private ed enti.<\/p>\n<\/li>\n<\/ul>\n<div data-hook=\"rcv-block9\"><\/div>\n<h3 id=\"viewer-40up\" class=\"eSWI6 _1j-51 blog-post-title-font yQX6br L4BKN_ _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Chi pu\u00f2 usufruire della misura agevolativa e in quale misura<\/span><\/h3>\n<p id=\"viewer-2j97f\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">La Legge di Bilancio per il 2021, nell\u2019ambito del \u201c<a class=\"_3Bkfb _1lsz7\" href=\"https:\/\/www.mise.gov.it\/index.php\/it\/transizione40\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" data-hook=\"linkViewer\"><u class=\"_3zM-5\">Nuovo Piano Nazionale Transizione 4.0<\/u><\/a>\u201d, ha esteso la misura agevolativa anche a:<\/span><\/p>\n<ul class=\"public-DraftStyleDefault-ul\">\n<li id=\"viewer-ann8p\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size public-DraftStyleDefault-reset _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">spese del personale relative ai formatori per le ore di partecipazione alla formazione;<\/p>\n<\/li>\n<li id=\"viewer-22lnf\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">costi di esercizio relativi a formatori e partecipanti alla formazione direttamente connessi al progetto di formazione;<\/p>\n<\/li>\n<li id=\"viewer-btume\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">costi dei servizi di consulenza connessi al progetto di formazione;<\/p>\n<\/li>\n<li id=\"viewer-5ce7b\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">spese di personale relative ai partecipanti alla formazione e le spese generali indirette per le ore durante le quali i partecipanti hanno seguito la formazione.<\/p>\n<\/li>\n<\/ul>\n<p id=\"viewer-bv3l5\" class=\"mm8Nw _1j-51 roLFQS _1FoOD _3M0Fe Z63qyL roLFQS public-DraftStyleDefault-block-depth0 fixed-tab-size public-DraftStyleDefault-text-ltr\"><span class=\"_2PHJq public-DraftStyleDefault-ltr\">Il credito d\u2019imposta Formazione 4.0 \u00e8 riconosciuto in misura del:<\/span><\/p>\n<ul class=\"public-DraftStyleDefault-ul\">\n<li id=\"viewer-bmlmc\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size public-DraftStyleDefault-reset _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">50% delle spese e nel limite massimo annuale di \u20ac 300.000 per le piccole imprese<\/p>\n<\/li>\n<li id=\"viewer-etjeb\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">40% delle spese e nel limite massimo annuale di \u20ac 250.000 per le medie imprese<\/p>\n<\/li>\n<li id=\"viewer-880ep\" class=\"roLFQS ULPWlI _3Kjjs public-DraftStyleDefault-unorderedListItem public-DraftStyleDefault-depth0 public-DraftStyleDefault-list-ltr fixed-tab-size _1FoOD _3M0Fe Z63qyL roLFQS\">\n<p class=\"_1j-51 _1FoOD _3M0Fe Z63qyL roLFQS\">30% delle spese e nel limite massimo annuale di \u20ac 250.000 le grandi imprese.<\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Il credito d\u2019imposta Formazione 4.0 \u00e8 una misura agevolativa nazionale rivolta a tutte le imprese con lo scopo di stimolare e incentivare gli investimenti nella formazione del personale sulle materie inerenti alle tecnologie rilevanti, per favorire la trasformazione digitale. Il credito d\u2019imposta Formazione 4.0 \u00e8 utilizzabile in compensazione F24 a decorrere dal periodo di imposta [&hellip;]<\/p>","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-278","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/posts\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/comments?post=278"}],"version-history":[{"count":2,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/posts\/278\/revisions"}],"predecessor-version":[{"id":3197,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/posts\/278\/revisions\/3197"}],"wp:attachment":[{"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/media?parent=278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/categories?post=278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vca.partners\/en\/wp-json\/wp\/v2\/tags?post=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}